{"id":2364,"date":"2024-08-01T23:43:10","date_gmt":"2024-08-02T02:43:10","guid":{"rendered":"https:\/\/locababyekids.com.br\/sn\/?post_type=product&#038;p=2364"},"modified":"2024-08-01T23:48:05","modified_gmt":"2024-08-02T02:48:05","slug":"vestido-estampado-pink","status":"publish","type":"product","link":"https:\/\/locababyekids.com.br\/sn\/product\/vestido-estampado-pink\/","title":{"rendered":"Vestido Estampado &#8211; Pink"},"content":{"rendered":"<p>Vestido Estampado &#8211; Pink<\/p>\n<p>100% Poli\u00e9ster<br \/>\nSaia Tule<br \/>\n100% Poliamida<br \/>\nSaiote<br \/>\n100% Algod\u00e3o<\/p>\n<p>Tamanho P<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vestido Estampado &#8211; Pink 100% Poli\u00e9ster Saia Tule 100% Poliamida Saiote 100% Algod\u00e3o Tamanho P<\/p>\n","protected":false},"featured_media":2366,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[252],"product_tag":[],"class_list":{"0":"post-2364","1":"product","2":"type-product","3":"status-publish","6":"product_cat-vestidos","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/locababyekids.com.br\/sn\/wp-json\/wp\/v2\/product\/2364"}],"collection":[{"href":"https:\/\/locababyekids.com.br\/sn\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/locababyekids.com.br\/sn\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/locababyekids.com.br\/sn\/wp-json\/wp\/v2\/comments?post=2364"}],"version-history":[{"count":0,"href":"https:\/\/locababyekids.com.br\/sn\/wp-json\/wp\/v2\/product\/2364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/locababyekids.com.br\/sn\/wp-json\/wp\/v2\/media\/2366"}],"wp:attachment":[{"href":"https:\/\/locababyekids.com.br\/sn\/wp-json\/wp\/v2\/media?parent=2364"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/locababyekids.com.br\/sn\/wp-json\/wp\/v2\/product_cat?post=2364"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/locababyekids.com.br\/sn\/wp-json\/wp\/v2\/product_tag?post=2364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}